{"id":105575,"date":"2026-04-28T14:22:34","date_gmt":"2026-04-28T13:22:34","guid":{"rendered":"https:\/\/virtual-routes.org\/?post_type=open-call&#038;p=105575"},"modified":"2026-04-29T09:01:42","modified_gmt":"2026-04-29T08:01:42","slug":"formazione-di-sensibilizzazione-alla-simulazione-di-phishing","status":"publish","type":"open-call","link":"https:\/\/virtual-routes.org\/it\/invito-aperto\/formazione-di-sensibilizzazione-alla-simulazione-di-phishing\/","title":{"rendered":"Simulazione di phishing e formazione di sensibilizzazione"},"content":{"rendered":"<p>Selezioneremo fino a 15 organizzazioni con sede in Irlanda e Spagna che riceveranno l'accesso alla simulazione di phishing e alla formazione sulla sicurezza informatica.<\/p>\n<p>Il phishing rimane una delle forme pi\u00f9 comuni ed efficaci di attacco informatico. Questo servizio aiuta le organizzazioni a ridurre il rischio formando i dipendenti a riconoscere e rispondere ai tentativi di phishing, trasformandoli in una linea di difesa attiva.<\/p>\n<p>Attraverso questo bando aperto, le organizzazioni selezionate avranno accesso a una piattaforma che combina simulazioni realistiche di phishing con formazione interattiva, segnalazione attiva delle minacce e feedback continuo. Questo approccio aiuta a costruire una consapevolezza a lungo termine e supporta miglioramenti misurabili nel comportamento di sicurezza.<\/p>\n<p>Il servizio \u00e8 fornito in collaborazione con Phished, con sede a Lovanio, in Belgio. Phished offre una piattaforma completamente automatizzata, alimentata da AI e progettata per ridurre gli incidenti causati da errori umani.<\/p>\n<p>Combinando simulazioni personalizzate e informazioni in tempo reale sulle minacce, Phished aiuta le organizzazioni a rafforzare la loro posizione di sicurezza complessiva. Il suo Behavioral Risk Score\u00ae (BRS) tiene costantemente traccia dei progressi compiuti ed evidenzia le aree di miglioramento, consentendo alle organizzazioni di comprendere meglio e ridurre la loro esposizione alle minacce di phishing.<\/p>\n<p>Le organizzazioni selezionate riceveranno l'accesso alla piattaforma e il supporto per implementare e gestire efficacemente le simulazioni all'interno dei loro team.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Chi pu\u00f2 candidarsi<\/strong><\/h2>\n<p>Questa iniziativa \u00e8 aperta a un'ampia gamma di organizzazioni che contribuiscono al funzionamento e alla resilienza delle comunit\u00e0 a livello locale o regionale. Ci\u00f2 include organizzazioni non profit, enti pubblici, cooperative e organizzazioni private con un ruolo chiaramente orientato alla comunit\u00e0.<\/p>\n<p>Per domande, contattare: <a href=\"mailto:cy***********@************es.org\" data-original-string=\"U3cE6CUcKxORY4qYQcDsvQ==d01uogaU0U5mQuCkmEaSAqq+HmfVEFvIOWHoEi7f\/w\/cBi165ECcJkMAgF5MV9fWhU9\" title=\"Questo contatto \u00e8 stato codificato da Anti-Spam by CleanTalk. Fare clic per decodificare. Per completare la decodifica, assicurarsi che JavaScript sia abilitato nel browser.\"><span \n                data-original-string='PLq\/oSTM9c1eHYi2TkmH9Q==d01dC3aIG4bp3ES3oy3KZFjkh+nSuTitncac17E5ytC5oXfaMcn+8hgn2Wy71seZCTB'\n                class='apbct-email-encoder'\n                title='Questo contatto \u00e8 stato codificato da Anti-Spam by CleanTalk. Fare clic per decodificare. Per completare la decodifica, assicurarsi che JavaScript sia abilitato nel browser.'>cy***********@************es.org<\/span><\/a>.<\/p>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":true,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false},"class_list":["post-105575","open-call","type-open-call","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/virtual-routes.org\/it\/wp-json\/wp\/v2\/open-call\/105575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/virtual-routes.org\/it\/wp-json\/wp\/v2\/open-call"}],"about":[{"href":"https:\/\/virtual-routes.org\/it\/wp-json\/wp\/v2\/types\/open-call"}],"wp:attachment":[{"href":"https:\/\/virtual-routes.org\/it\/wp-json\/wp\/v2\/media?parent=105575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}